{"id":5965,"date":"2024-10-07T00:00:00","date_gmt":"2024-10-06T22:00:00","guid":{"rendered":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/"},"modified":"2025-10-31T11:02:15","modified_gmt":"2025-10-31T10:02:15","slug":"las-amantes-de-picasso","status":"publish","type":"product","link":"https:\/\/navonaed.com\/ca\/libro\/las-amantes-de-picasso\/","title":{"rendered":"Las amantes de Picasso"},"content":{"rendered":"<p><b>Amor\u00edos, esc\u00e1ndalos y arte: la voz de las mujeres que vivieron a la sombra de Picasso.<\/b><\/p>\n<p>Nueva York, 1953.<br \/>\nAspirante a periodista, Alana Olson siempre ha sentido una gran fascinaci\u00f3n por la figura de Picasso. Su gran inter\u00e9s la conduce a una serie de entrevistas \u00edntimas con Sara Murphy e Ir\u00e8ne Lagut, dos figuras clave del vibrante c\u00edrculo social franc\u00e9s del artista. Glamurosas y esquivas, las mujeres de Picasso siempre vivieron a la sombra de su fama.<\/p>\n<p>Jeanne Mackin nos redirige a una \u00e9poca que lleva fascin\u00e1ndonos desde hace m\u00e1s de un siglo, ofreciendo esta vez a mujeres amantes y musas la oportunidad de salir de los cuadros que inspiraron y colocarse en el papel de protagonistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>9788410180062<br \/>Jeanne Mackin<\/p>\n","protected":false},"featured_media":5082,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[141],"product_tag":[],"class_list":["post-5965","product","type-product","status-publish","has-post-thumbnail","product_cat-serie-m","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las amantes de Picasso - Editorial Navona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las amantes de Picasso - Editorial Navona\" \/>\n<meta property=\"og:description\" content=\"9788410180062Jeanne Mackin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/\" \/>\n<meta property=\"og:site_name\" content=\"Editorial Navona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Reemocioart\/100076073310442\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T10:02:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/navonaed.com\/wp-content\/uploads\/las_amantes_de_picasso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"1368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/navonaed.com\\\/libro\\\/las-amantes-de-picasso\\\/\",\"url\":\"https:\\\/\\\/navonaed.com\\\/libro\\\/las-amantes-de-picasso\\\/\",\"name\":\"Las amantes de Picasso - Editorial Navona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/navonaed.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/navonaed.com\\\/libro\\\/las-amantes-de-picasso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/navonaed.com\\\/libro\\\/las-amantes-de-picasso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/navonaed.com\\\/wp-content\\\/uploads\\\/las_amantes_de_picasso.jpg\",\"datePublished\":\"2024-10-06T22:00:00+00:00\",\"dateModified\":\"2025-10-31T10:02:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/navonaed.com\\\/libro\\\/las-amantes-de-picasso\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/navonaed.com\\\/libro\\\/las-amantes-de-picasso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/navonaed.com\\\/libro\\\/las-amantes-de-picasso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/navonaed.com\\\/wp-content\\\/uploads\\\/las_amantes_de_picasso.jpg\",\"contentUrl\":\"https:\\\/\\\/navonaed.com\\\/wp-content\\\/uploads\\\/las_amantes_de_picasso.jpg\",\"width\":900,\"height\":1368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/navonaed.com\\\/libro\\\/las-amantes-de-picasso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/navonaed.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e0leg\",\"item\":\"https:\\\/\\\/navonaed.com\\\/ca\\\/cataleg\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Las amantes de Picasso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/navonaed.com\\\/#website\",\"url\":\"https:\\\/\\\/navonaed.com\\\/\",\"name\":\"Editorial Navona\",\"description\":\"Nos gustan los libros\",\"publisher\":{\"@id\":\"https:\\\/\\\/navonaed.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/navonaed.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/navonaed.com\\\/#organization\",\"name\":\"Editorial Navona\",\"url\":\"https:\\\/\\\/navonaed.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/navonaed.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/navonaed.com\\\/wp-content\\\/uploads\\\/logo-navona.svg\",\"contentUrl\":\"https:\\\/\\\/navonaed.com\\\/wp-content\\\/uploads\\\/logo-navona.svg\",\"width\":155,\"height\":32,\"caption\":\"Editorial Navona\"},\"image\":{\"@id\":\"https:\\\/\\\/navonaed.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Reemocioart\\\/100076073310442\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las amantes de Picasso - Editorial Navona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/","og_locale":"ca_ES","og_type":"article","og_title":"Las amantes de Picasso - Editorial Navona","og_description":"9788410180062Jeanne Mackin","og_url":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/","og_site_name":"Editorial Navona","article_publisher":"https:\/\/www.facebook.com\/people\/Reemocioart\/100076073310442\/","article_modified_time":"2025-10-31T10:02:15+00:00","og_image":[{"width":900,"height":1368,"url":"https:\/\/navonaed.com\/wp-content\/uploads\/las_amantes_de_picasso.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/","url":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/","name":"Las amantes de Picasso - Editorial Navona","isPartOf":{"@id":"https:\/\/navonaed.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/#primaryimage"},"image":{"@id":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/#primaryimage"},"thumbnailUrl":"https:\/\/navonaed.com\/wp-content\/uploads\/las_amantes_de_picasso.jpg","datePublished":"2024-10-06T22:00:00+00:00","dateModified":"2025-10-31T10:02:15+00:00","breadcrumb":{"@id":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/#primaryimage","url":"https:\/\/navonaed.com\/wp-content\/uploads\/las_amantes_de_picasso.jpg","contentUrl":"https:\/\/navonaed.com\/wp-content\/uploads\/las_amantes_de_picasso.jpg","width":900,"height":1368},{"@type":"BreadcrumbList","@id":"https:\/\/navonaed.com\/libro\/las-amantes-de-picasso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/navonaed.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e0leg","item":"https:\/\/navonaed.com\/ca\/cataleg\/"},{"@type":"ListItem","position":3,"name":"Las amantes de Picasso"}]},{"@type":"WebSite","@id":"https:\/\/navonaed.com\/#website","url":"https:\/\/navonaed.com\/","name":"Editorial Navona","description":"Nos gustan los libros","publisher":{"@id":"https:\/\/navonaed.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/navonaed.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/navonaed.com\/#organization","name":"Editorial Navona","url":"https:\/\/navonaed.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/navonaed.com\/#\/schema\/logo\/image\/","url":"https:\/\/navonaed.com\/wp-content\/uploads\/logo-navona.svg","contentUrl":"https:\/\/navonaed.com\/wp-content\/uploads\/logo-navona.svg","width":155,"height":32,"caption":"Editorial Navona"},"image":{"@id":"https:\/\/navonaed.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Reemocioart\/100076073310442\/"]}]}},"_links":{"self":[{"href":"https:\/\/navonaed.com\/ca\/wp-json\/wp\/v2\/product\/5965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/navonaed.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/navonaed.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/navonaed.com\/ca\/wp-json\/wp\/v2\/media\/5082"}],"wp:attachment":[{"href":"https:\/\/navonaed.com\/ca\/wp-json\/wp\/v2\/media?parent=5965"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/navonaed.com\/ca\/wp-json\/wp\/v2\/product_brand?post=5965"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/navonaed.com\/ca\/wp-json\/wp\/v2\/product_cat?post=5965"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/navonaed.com\/ca\/wp-json\/wp\/v2\/product_tag?post=5965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}